{"id":23162,"date":"2025-05-28T15:35:50","date_gmt":"2025-05-28T13:35:50","guid":{"rendered":"https:\/\/cubeconcepts.de\/?p=23162"},"modified":"2026-06-12T07:18:01","modified_gmt":"2026-06-12T05:18:01","slug":"instalaciones-de-clientes-para-la-generacion-de-energia-para-inquilinos-bajo-presion-tras-las-sentencias-del-tjue-y-el-bgh","status":"publish","type":"post","link":"https:\/\/cubeconcepts.de\/es\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/","title":{"rendered":"Plantillas de clientes y suministro el\u00e9ctrico a inquilinos bajo presi\u00f3n seg\u00fan sentencia del TJUE y BGH"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El marco legal para los conceptos de suministro de energ\u00eda descentralizado, <strong>Instalaciones del cliente<\/strong> y <strong>Corriente para inquilinos<\/strong> deben ser regulados nuevamente por el gobierno federal alem\u00e1n. El punto de partida es la sentencia del Tribunal de Justicia de la Uni\u00f3n Europea (TJUE) de 28 de noviembre de 2024 (asunto C-293\/23), que ahora adquiere efecto nacional por una resoluci\u00f3n del Tribunal Federal de Justicia (BGH) de 13 de mayo de 2025 (n\u00fam. de caso EnVR 83\/20). El llamado. <strong>Privilegio de usuario del cliente<\/strong> seg\u00fan el \u00a7 3, n\u00famero 24a de la EnWG, que hasta ahora ha sido un pilar fundamental para los proyectos de suministro el\u00e9ctrico para inquilinos, las soluciones de barrio y las redes de autoconsumo industrial, es <strong>en gran parte ca\u00eddo<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sentencia del TJUE: sin normas especiales para instalaciones de clientes y modelos de suministro el\u00e9ctrico para inquilinos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El TJUE aclar\u00f3 que <strong>normativa nacional especial<\/strong> c\u00f3mo el privilegio alem\u00e1n de las instalaciones de clientes no es compatible con la Directiva de la UE sobre el mercado interior de la electricidad (DOUE 2019\/944). En particular, se considera inadmisible excluir las infraestructuras energ\u00e9ticas del concepto de red de distribuci\u00f3n definido por el Derecho de la Uni\u00f3n mediante criterios nacionales. Por lo tanto, la pr\u00e1ctica alemana hasta ahora contradice el marco jur\u00eddico europeo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el TJUE, todas las l\u00edneas a trav\u00e9s de las cuales <strong>Electricidad al consumidor final<\/strong> se entrega, <strong>b\u00e1sicamente como redes de distribuci\u00f3n<\/strong> \u2013 independientemente de su tama\u00f1o, estructura t\u00e9cnica o del hecho de que solo abastezcan un \u00fanico edificio o un \u00e1rea delimitada. Por lo tanto, las categor\u00edas especiales nacionales, como la llamada instalaci\u00f3n del cliente, no podr\u00e1n basarse en caracter\u00edsticas adicionales como el n\u00famero de consumidores finales, el flujo de electricidad o la extensi\u00f3n espacial para eximir a determinadas instalaciones de la regulaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la pr\u00e1ctica, esto significa: <strong>Operador<\/strong> tales sistemas de suministro de energ\u00eda <strong>como operador de red de distribuci\u00f3n<\/strong>. En el futuro se les aplicar\u00e1n los mismos requisitos reglamentarios. Estos incluyen, entre otros, la obligaci\u00f3n de desvinculaci\u00f3n de propiedad y operativa, la regulaci\u00f3n de los peajes de red y obligaciones exhaustivas de acceso y transparencia. Las exenciones de estas obligaciones solo son posibles en los casos previstos expresamente en el Derecho de la Uni\u00f3n, por ejemplo, para redes de distribuci\u00f3n cerradas o empresas de energ\u00eda ciudadana.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sentencia del Tribunal Supremo Federal (BGH): Implementaci\u00f3n nacional de las directivas del Tribunal de Justicia de la Uni\u00f3n Europea (TJUE)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El BGH ha recogido, confirmado y aplicado de manera consecuente la jurisprudencia del TJUE a un proyecto concreto de suministro de energ\u00eda para inquilinos. En este proceso, el tribunal aclar\u00f3 que las instalaciones de consumo y el suministro de energ\u00eda para inquilinos solo pueden interpretarse de conformidad con la Directiva de la UE sobre el mercado interior de la electricidad (2019\/944). En la pr\u00e1ctica, esto significa: una instalaci\u00f3n de consumo solo existe cuando no se produce suministro de electricidad a terceros a cambio de una tarifa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el caso en cuesti\u00f3n, un promotor de proyectos planeaba abastecer 250 viviendas a trav\u00e9s de su propia red de canalizaci\u00f3n privada. Dado que la electricidad deb\u00eda suministrarse a varios consumidores finales a cambio de una tarifa, el BGH calific\u00f3 la red como <strong>red de distribuci\u00f3n sujeta a regulaci\u00f3n<\/strong>. El trato especial previo de tales estructuras a trav\u00e9s del privilegio de las instalaciones del cliente ha sido, por lo tanto, efectivamente derogado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La consecuencia legal: Los operadores de las instalaciones correspondientes est\u00e1n ahora sujetos <strong>completo<\/strong> <strong>derecho energ\u00e9tico<\/strong>. Esto incluye, por ejemplo, las obligaciones de pago de <strong>Tarifas de red<\/strong>, para asumir la <strong>Responsabilidad del c\u00edrculo de balance<\/strong> o para el establecimiento de un adecuado <strong>Operador de puntos de medida<\/strong>. En particular, se ven afectados los modelos de electricidad para inquilinos, como los que utilizan sistemas fotovoltaicos, las soluciones de barrios con cogeneraci\u00f3n o energ\u00edas renovables para el suministro de \u00e1reas industriales, por ejemplo, en pol\u00edgonos industriales, as\u00ed como los modelos de suministro comunitarios en edificios m\u00e1s grandes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Impacto para operadores de instalaciones de clientes y modelos de venta de electricidad a inquilinos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Muchos proyectos de instalaciones de clientes y de suministro a inquilinos se basan hasta ahora en los privilegios del \u00a7 3, n\u00famero 24a de la EnWG. Esto les proporcionaba ventajas econ\u00f3micas considerables, ya que no se incurr\u00eda en cargos de red, recargos ni otras obligaciones regulatorias. Sin embargo, con la reclasificaci\u00f3n de dichas instalaciones como redes de distribuci\u00f3n sujetas a regulaci\u00f3n, estos privilegios desaparecen, lo que pone fundamentalmente en entredicho la rentabilidad de numerosos proyectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Particularmente problem\u00e1tico es el reci\u00e9n creado <strong>Inseguridad jur\u00eddica para instalaciones existentes<\/strong>. Dado que la clasificaci\u00f3n como instalaci\u00f3n de cliente se ha realizado hasta ahora generalmente sin control oficial, ahora se temen medidas regulatorias posteriores, como reclamaciones retroactivas, reestructuraciones u la obligaci\u00f3n de volver a registrarse como red de distribuci\u00f3n cerrada. Esto afecta no solo a las estructuras de suministro nuevas, sino tambi\u00e9n a las que llevan mucho tiempo en funcionamiento en barrios residenciales o zonas industriales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">incluso los mecanismos de financiaci\u00f3n existentes, como el <strong>Complemento de electricidad para inquilinos<\/strong> seg\u00fan el \u00a7 21, apartado 3 de la EEG, se ven presionados. Esta financiaci\u00f3n exige que la electricidad no se conduzca a trav\u00e9s de una red de suministro p\u00fablico. Sin embargo, si una instalaci\u00f3n de cliente anteriormente privilegiada se clasifica como una red de distribuci\u00f3n regular, esta condici\u00f3n ya no se cumple, y el <strong>Derecho a subsidio\/ayuda\/subvenci\u00f3n caduca<\/strong>. Numerosos proyectos ya no ser\u00edan econ\u00f3micamente viables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Aumenta la presi\u00f3n de acci\u00f3n para las instalaciones de clientes y el autoconsumo compartido<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los operadores y desarrolladores de instalaciones de clientes y proyectos de electricidad para inquilinos se encuentran considerablemente inseguros tras las sentencias y exigen nuevas regulaciones por parte de la legislaci\u00f3n alemana. Actualmente se cierne una <strong>Cancelaci\u00f3n de proyectos existentes<\/strong> y <strong>Inversiones<\/strong> en nuevos proyectos <strong>almacenar<\/strong>. Las empresas se enfrentan ahora al desaf\u00edo de reevaluar, adaptar o, en su caso, reestructurar sus estructuras de suministro de energ\u00eda como redes de distribuci\u00f3n cerradas. Sin una nueva regulaci\u00f3n, se enfrentan a nuevas obligaciones, como la segregaci\u00f3n contable, la recaudaci\u00f3n y el pago de tarifas de red y recargos (como los recargos KWKG, offshore o \u00a7 19 StromNEV), la concesi\u00f3n de acceso a la red a terceros, as\u00ed como amplias obligaciones de notificaci\u00f3n y prueba ante los organismos reguladores. Adem\u00e1s, todav\u00eda existen problemas en la generaci\u00f3n de la <a href=\"https:\/\/cubeconcepts.de\/herkunftsnachweise-buerokratie-bremst-gruenen-mieterstrom\/\">Certificados de origen: La burocracia frena la electricidad verde para inquilinos<\/a>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Perspectivas para los operadores e impulsos para la legislaci\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los operadores y promotores de proyectos de modelos de suministro de electricidad descentralizado deben realizar ahora un inventario cr\u00edtico de sus instalaciones existentes. Debe examinarse si las configuraciones t\u00e9cnicas y operativas de las instalaciones cumplen los criterios del TJUE para una red de distribuci\u00f3n sujeta a regulaci\u00f3n. Cuando sea as\u00ed, los conceptos existentes deber\u00e1n adaptarse o ser sustituidos por <strong>modelos alternativos jur\u00eddicamente v\u00e1lidos<\/strong> ser\u00e1n reemplazados. Un enfoque posible para esto reside en conceptos de suministro h\u00edbridos, en los cuales la electricidad no se suministra exclusivamente a trav\u00e9s de una red interna, sino que se proporciona de forma complementaria a una tarifa de suministro b\u00e1sico existente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mismo tiempo, el gobierno federal alem\u00e1n est\u00e1 llamado a adaptar el sistema de red a las directrices europeas y, al mismo tiempo, a crear soluciones pr\u00e1cticas para estructuras m\u00e1s peque\u00f1as y cercanas al consumidor. A nivel de la UE, la Directiva sobre el mercado interior de la electricidad ofrece m\u00e1rgenes de maniobra, por ejemplo, mediante el reconocimiento de redes de distribuci\u00f3n cerradas y comunidades de energ\u00eda ciudadana, que pueden quedar exentas de requisitos reglamentarios bajo ciertas condiciones. A nivel nacional, las llamadas redes de \u00e1rea podr\u00edan ofrecer soluciones. Esto permitir\u00eda crear una base jur\u00eddicamente segura y econ\u00f3micamente viable para muchos modelos de suministro descentralizados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se deber\u00eda adaptar la Ley de Energ\u00edas Renovables (EEG): Para seguir permitiendo la prima de energ\u00eda para inquilinos, los modelos con distribuci\u00f3n interna de electricidad deber\u00edan seguir siendo subvencionables, siempre que se garantice la transparencia, la protecci\u00f3n del consumidor y la no discriminaci\u00f3n. Solo mediante una interacci\u00f3n de medidas t\u00e9cnicas, regulatorias y pol\u00edticas de este tipo se podr\u00e1n implementar con \u00e9xito conceptos de energ\u00eda descentralizada en el futuro.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Reenfoque urgente en instalaciones de clientes y suministro el\u00e9ctrico a inquilinos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La sentencia del TJUE y el posterior auto del BGH aportan claridad, pero al mismo tiempo gran incertidumbre. La normativa vigente en Alemania sobre instalaciones para clientes y suministro de electricidad a inquilinos es, por tanto, contraria al derecho de la Uni\u00f3n. Ahora es el legislador quien debe crear a corto plazo condiciones marco pr\u00e1cticas y conformes al derecho de la Uni\u00f3n para no frenar la transici\u00f3n energ\u00e9tica en el \u00e1mbito comercial y urbano. Sin disposiciones transitorias jur\u00eddicamente seguras y una r\u00e1pida adaptaci\u00f3n del derecho energ\u00e9tico, se corre el riesgo de un atasco en las inversiones, la interrupci\u00f3n de proyectos y un retroceso en la transici\u00f3n energ\u00e9tica descentralizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Las sentencias del TJUE (2024) y del BGH (2025) han hecho en gran medida obsoleto el privilegio de las instalaciones de clientes (\u00a7 3 n.\u00ba 24a de la EnWG): las l\u00edneas con suministro de electricidad cobrado a terceros se consideran ahora redes de distribuci\u00f3n sujetas a regulaci\u00f3n. Los operadores de modelos de electricidad para inquilinos o de \u00e1reas estar\u00e1n sujetos a estrictos requisitos en el futuro.<\/p>","protected":false},"author":3,"featured_media":23165,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[7,60],"tags":[],"class_list":["post-23162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solar-news","category-regulatorik-esg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kundenanlagen &amp; Mieterstrom unter Druck CUBE CONCEPTS<\/title>\n<meta name=\"description\" content=\"Kundenanlagen &amp; Mieterstrom geraten nach EuGH- und BGH-Urteil unter Druck. Jetzt ist der deutsche Gesetzgeber gefragt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cubeconcepts.de\/es\/instalaciones-de-clientes-para-la-generacion-de-energia-para-inquilinos-bajo-presion-tras-las-sentencias-del-tjue-y-el-bgh\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kundenanlagen &amp; Mieterstrom unter Druck CUBE CONCEPTS\" \/>\n<meta property=\"og:description\" content=\"Kundenanlagen &amp; Mieterstrom geraten nach EuGH- und BGH-Urteil unter Druck. Jetzt ist der deutsche Gesetzgeber gefragt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cubeconcepts.de\/es\/instalaciones-de-clientes-para-la-generacion-de-energia-para-inquilinos-bajo-presion-tras-las-sentencias-del-tjue-y-el-bgh\/\" \/>\n<meta property=\"og:site_name\" content=\"CUBE CONCEPTS\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-28T13:35:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-12T05:18:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2025\/05\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Guido Steenmans\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guido Steenmans\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/\"},\"author\":{\"name\":\"Guido Steenmans\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/#\\\/schema\\\/person\\\/2c762e4ca1ea252f42f23ab33248856e\"},\"headline\":\"Kundenanlagen &amp; Mieterstrom nach EuGH- und BGH-Urteil unter Druck\",\"datePublished\":\"2025-05-28T13:35:50+00:00\",\"dateModified\":\"2026-06-12T05:18:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/\"},\"wordCount\":1047,\"publisher\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cubeconcepts.de\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg\",\"articleSection\":[\"Energiemarkt News\",\"Regulatorik &amp; ESG\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/\",\"url\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/\",\"name\":\"Kundenanlagen & Mieterstrom unter Druck CUBE CONCEPTS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cubeconcepts.de\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg\",\"datePublished\":\"2025-05-28T13:35:50+00:00\",\"dateModified\":\"2026-06-12T05:18:01+00:00\",\"description\":\"Kundenanlagen & Mieterstrom geraten nach EuGH- und BGH-Urteil unter Druck. Jetzt ist der deutsche Gesetzgeber gefragt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cubeconcepts.de\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/cubeconcepts.de\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg\",\"width\":2560,\"height\":1690,\"caption\":\"Kundenanlagen-Mieterstrom-EuGH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cubeconcepts.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kundenanlagen &amp; Mieterstrom nach EuGH- und BGH-Urteil unter Druck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/\",\"name\":\"CUBE CONCEPTS\",\"description\":\"Energiesysteme f\u00fcr Unternehmen\",\"publisher\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/#organization\",\"name\":\"CUBE CONCEPTS\",\"url\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cubeconcepts.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/CUBE_CONCEPT-Logo.png\",\"contentUrl\":\"https:\\\/\\\/cubeconcepts.de\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/CUBE_CONCEPT-Logo.png\",\"width\":644,\"height\":207,\"caption\":\"CUBE CONCEPTS\"},\"image\":{\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/fr\\\/#\\\/schema\\\/person\\\/2c762e4ca1ea252f42f23ab33248856e\",\"name\":\"Guido Steenmans\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cubeconcepts.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Guido-Steenmanns-hoch-scaled-1-96x96.jpg\",\"url\":\"https:\\\/\\\/cubeconcepts.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Guido-Steenmanns-hoch-scaled-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/cubeconcepts.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-Guido-Steenmanns-hoch-scaled-1-96x96.jpg\",\"caption\":\"Guido Steenmans\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kundenanlagen & Mieterstrom unter Druck CUBE CONCEPTS","description":"Kundenanlagen & Mieterstrom geraten nach EuGH- und BGH-Urteil unter Druck. Jetzt ist der deutsche Gesetzgeber gefragt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cubeconcepts.de\/es\/instalaciones-de-clientes-para-la-generacion-de-energia-para-inquilinos-bajo-presion-tras-las-sentencias-del-tjue-y-el-bgh\/","og_locale":"es_ES","og_type":"article","og_title":"Kundenanlagen & Mieterstrom unter Druck CUBE CONCEPTS","og_description":"Kundenanlagen & Mieterstrom geraten nach EuGH- und BGH-Urteil unter Druck. Jetzt ist der deutsche Gesetzgeber gefragt.","og_url":"https:\/\/cubeconcepts.de\/es\/instalaciones-de-clientes-para-la-generacion-de-energia-para-inquilinos-bajo-presion-tras-las-sentencias-del-tjue-y-el-bgh\/","og_site_name":"CUBE CONCEPTS","article_published_time":"2025-05-28T13:35:50+00:00","article_modified_time":"2026-06-12T05:18:01+00:00","og_image":[{"width":2560,"height":1690,"url":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2025\/05\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg","type":"image\/jpeg"}],"author":"Guido Steenmans","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Guido Steenmans","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/#article","isPartOf":{"@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/"},"author":{"name":"Guido Steenmans","@id":"https:\/\/cubeconcepts.de\/fr\/#\/schema\/person\/2c762e4ca1ea252f42f23ab33248856e"},"headline":"Kundenanlagen &amp; Mieterstrom nach EuGH- und BGH-Urteil unter Druck","datePublished":"2025-05-28T13:35:50+00:00","dateModified":"2026-06-12T05:18:01+00:00","mainEntityOfPage":{"@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/"},"wordCount":1047,"publisher":{"@id":"https:\/\/cubeconcepts.de\/fr\/#organization"},"image":{"@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/#primaryimage"},"thumbnailUrl":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2025\/05\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg","articleSection":["Energiemarkt News","Regulatorik &amp; ESG"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/","url":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/","name":"Kundenanlagen & Mieterstrom unter Druck CUBE CONCEPTS","isPartOf":{"@id":"https:\/\/cubeconcepts.de\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/#primaryimage"},"image":{"@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/#primaryimage"},"thumbnailUrl":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2025\/05\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg","datePublished":"2025-05-28T13:35:50+00:00","dateModified":"2026-06-12T05:18:01+00:00","description":"Kundenanlagen & Mieterstrom geraten nach EuGH- und BGH-Urteil unter Druck. Jetzt ist der deutsche Gesetzgeber gefragt.","breadcrumb":{"@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/#primaryimage","url":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2025\/05\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg","contentUrl":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2025\/05\/Kundenanlagen-Miterstrom-EuGH-scaled.jpeg","width":2560,"height":1690,"caption":"Kundenanlagen-Mieterstrom-EuGH"},{"@type":"BreadcrumbList","@id":"https:\/\/cubeconcepts.de\/kundenanlagen-mieterstrom-nach-eugh-und-bgh-urteil-unter-druck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cubeconcepts.de\/"},{"@type":"ListItem","position":2,"name":"Kundenanlagen &amp; Mieterstrom nach EuGH- und BGH-Urteil unter Druck"}]},{"@type":"WebSite","@id":"https:\/\/cubeconcepts.de\/fr\/#website","url":"https:\/\/cubeconcepts.de\/fr\/","name":"CONCEPTOS DE CUBO","description":"Sistemas de energ\u00eda para empresas","publisher":{"@id":"https:\/\/cubeconcepts.de\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cubeconcepts.de\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cubeconcepts.de\/fr\/#organization","name":"CONCEPTOS DE CUBO","url":"https:\/\/cubeconcepts.de\/fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cubeconcepts.de\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2023\/01\/CUBE_CONCEPT-Logo.png","contentUrl":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2023\/01\/CUBE_CONCEPT-Logo.png","width":644,"height":207,"caption":"CUBE CONCEPTS"},"image":{"@id":"https:\/\/cubeconcepts.de\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cubeconcepts.de\/fr\/#\/schema\/person\/2c762e4ca1ea252f42f23ab33248856e","name":"Guido Steenmans","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2025\/11\/cropped-Guido-Steenmanns-hoch-scaled-1-96x96.jpg","url":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2025\/11\/cropped-Guido-Steenmanns-hoch-scaled-1-96x96.jpg","contentUrl":"https:\/\/cubeconcepts.de\/wp-content\/uploads\/2025\/11\/cropped-Guido-Steenmanns-hoch-scaled-1-96x96.jpg","caption":"Guido Steenmans"}}]}},"_links":{"self":[{"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/posts\/23162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/comments?post=23162"}],"version-history":[{"count":0,"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/posts\/23162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/media\/23165"}],"wp:attachment":[{"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/media?parent=23162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/categories?post=23162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cubeconcepts.de\/es\/wp-json\/wp\/v2\/tags?post=23162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}